{"id":66272,"date":"2026-07-14T11:03:01","date_gmt":"2026-07-14T10:03:01","guid":{"rendered":"https:\/\/elmawkie.dz\/fr\/?p=66272"},"modified":"2026-07-14T11:08:13","modified_gmt":"2026-07-14T10:08:13","slug":"une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran","status":"publish","type":"post","link":"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/","title":{"rendered":"Une campagne nationale de bilans m\u00e9dicaux pour les sportifs lanc\u00e9e depuis Oran"},"content":{"rendered":"\n<p><strong>L\u2019Association nationale alg\u00e9rienne de m\u00e9decine du sport (ANAMS) a entam\u00e9, depuis la wilaya d\u2019Oran, une vaste campagne nationale de bilans m\u00e9dicaux destin\u00e9e aux sportifs en pr\u00e9vision de la saison sportive 2026-2027. L\u2019op\u00e9ration sera progressivement d\u00e9ploy\u00e9e dans l\u2019ensemble des wilayas du pays, selon un communiqu\u00e9 rendu public mardi.<\/strong><\/p>\n\n\n\n<p>Cette initiative vise \u00e0 renforcer le suivi m\u00e9dical des athl\u00e8tes, \u00e0 promouvoir la pr\u00e9vention et \u00e0 garantir une meilleure pr\u00e9paration physique et sanitaire avant le d\u00e9but des comp\u00e9titions. L\u2019objectif est \u00e9galement de contribuer \u00e0 la d\u00e9tection pr\u00e9coce d\u2019\u00e9ventuels probl\u00e8mes de sant\u00e9 et de limiter les risques de blessures.<\/p>\n\n\n\n<p>R\u00e9alis\u00e9e en coordination avec la clinique El Kendi d\u2019Oran, sp\u00e9cialis\u00e9e en m\u00e9decine du sport et en r\u00e9\u00e9ducation fonctionnelle, la campagne comprend une s\u00e9rie d\u2019examens m\u00e9dicaux complets, notamment un bilan cardiovasculaire avec \u00e9lectrocardiogramme (ECG), une \u00e9valuation des fonctions respiratoires, un examen de l\u2019appareil locomoteur, des analyses biologiques ainsi que diff\u00e9rentes mesures anthropom\u00e9triques et \u00e9valuations physiques.<\/p>\n\n\n\n<p>L\u2019ANAMS, dont le si\u00e8ge est bas\u00e9 \u00e0 Oran, a invit\u00e9 les clubs sportifs \u00e0 prendre attache avec l\u2019association via sa page officielle afin de fixer les rendez-vous n\u00e9cessaires et b\u00e9n\u00e9ficier des examens propos\u00e9s dans le cadre de cette campagne nationale.<\/p>\n\n\n\n<p>\u00c0 travers cette op\u00e9ration, l\u2019association r\u00e9affirme sa volont\u00e9 d\u2019ancrer la culture de la pr\u00e9vention au sein du mouvement sportif et d\u2019accompagner les athl\u00e8tes par un suivi m\u00e9dical r\u00e9gulier, consid\u00e9r\u00e9 comme un levier essentiel pour pr\u00e9server leur sant\u00e9 et optimiser leurs performances.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Association nationale alg\u00e9rienne de m\u00e9decine du sport (ANAMS) a entam\u00e9, depuis la wilaya d\u2019Oran, une vaste campagne nationale de bilans m\u00e9dicaux destin\u00e9e aux sportifs en pr\u00e9vision de la saison sportive 2026-2027. L\u2019op\u00e9ration sera progressivement d\u00e9ploy\u00e9e dans l\u2019ensemble des wilayas du pays, selon un communiqu\u00e9 rendu public mardi. Cette initiative vise \u00e0 renforcer le suivi m\u00e9dical &hellip;<\/p>\n","protected":false},"author":9,"featured_media":66281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57],"tags":[6610,75,6609,1313],"class_list":["post-66272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-anams","tag-oran","tag-sportifs","tag-une-campagne-nationale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v22.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Une campagne nationale de bilans m\u00e9dicaux pour les sportifs lanc\u00e9e depuis Oran - El Mawkie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une campagne nationale de bilans m\u00e9dicaux pour les sportifs lanc\u00e9e depuis Oran\" \/>\n<meta property=\"og:description\" content=\"L\u2019Association nationale alg\u00e9rienne de m\u00e9decine du sport (ANAMS) a entam\u00e9, depuis la wilaya d\u2019Oran, une vaste campagne nationale de bilans m\u00e9dicaux destin\u00e9e aux sportifs en pr\u00e9vision de la saison sportive 2026-2027. L\u2019op\u00e9ration sera progressivement d\u00e9ploy\u00e9e dans l\u2019ensemble des wilayas du pays, selon un communiqu\u00e9 rendu public mardi. Cette initiative vise \u00e0 renforcer le suivi m\u00e9dical &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/\" \/>\n<meta property=\"og:site_name\" content=\"El Mawkie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100088407094989&amp;locale=fr_FR\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T10:03:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T10:08:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elmawkie.dz\/fr\/wp-content\/uploads\/2026\/07\/14a15ec5-88d5-46a6-8310-938e3eb8ff54.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"778\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"R\u00e9daction\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"R\u00e9daction\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/\"},\"author\":{\"name\":\"R\u00e9daction\",\"@id\":\"https:\/\/elmawkie.dz\/fr\/#\/schema\/person\/e7bd59d6467874ba5c4723d8a9f0a63c\"},\"headline\":\"Une campagne nationale de bilans m\u00e9dicaux pour les sportifs lanc\u00e9e depuis Oran\",\"datePublished\":\"2026-07-14T10:03:01+00:00\",\"dateModified\":\"2026-07-14T10:08:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/\"},\"wordCount\":291,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/elmawkie.dz\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elmawkie.dz\/fr\/wp-content\/uploads\/2026\/07\/14a15ec5-88d5-46a6-8310-938e3eb8ff54.jpeg\",\"keywords\":[\"ANAMS\",\"Oran\",\"sportifs\",\"une campagne nationale\"],\"articleSection\":[\"Sport\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/\",\"url\":\"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/\",\"name\":\"Une campagne nationale de bilans m\u00e9dicaux pour les sportifs lanc\u00e9e depuis Oran - El Mawkie\",\"isPartOf\":{\"@id\":\"https:\/\/elmawkie.dz\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elmawkie.dz\/fr\/wp-content\/uploads\/2026\/07\/14a15ec5-88d5-46a6-8310-938e3eb8ff54.jpeg\",\"datePublished\":\"2026-07-14T10:03:01+00:00\",\"dateModified\":\"2026-07-14T10:08:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/#primaryimage\",\"url\":\"https:\/\/elmawkie.dz\/fr\/wp-content\/uploads\/2026\/07\/14a15ec5-88d5-46a6-8310-938e3eb8ff54.jpeg\",\"contentUrl\":\"https:\/\/elmawkie.dz\/fr\/wp-content\/uploads\/2026\/07\/14a15ec5-88d5-46a6-8310-938e3eb8ff54.jpeg\",\"width\":1280,\"height\":778},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/elmawkie.dz\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Une campagne nationale de bilans m\u00e9dicaux pour les sportifs lanc\u00e9e depuis Oran\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elmawkie.dz\/fr\/#website\",\"url\":\"https:\/\/elmawkie.dz\/fr\/\",\"name\":\"EL MAWKIE\",\"description\":\"Journal \u00c9lectronique Alg\u00e9rien\",\"publisher\":{\"@id\":\"https:\/\/elmawkie.dz\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elmawkie.dz\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elmawkie.dz\/fr\/#organization\",\"name\":\"EL MAWKIE\",\"url\":\"https:\/\/elmawkie.dz\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/elmawkie.dz\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elmawkie.dz\/fr\/wp-content\/uploads\/2024\/05\/logo1.png\",\"contentUrl\":\"https:\/\/elmawkie.dz\/fr\/wp-content\/uploads\/2024\/05\/logo1.png\",\"width\":1648,\"height\":652,\"caption\":\"EL MAWKIE\"},\"image\":{\"@id\":\"https:\/\/elmawkie.dz\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100088407094989&locale=fr_FR\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/elmawkie.dz\/fr\/#\/schema\/person\/e7bd59d6467874ba5c4723d8a9f0a63c\",\"name\":\"R\u00e9daction\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/elmawkie.dz\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f0f773456344da4d2788c054a3d30a0c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f0f773456344da4d2788c054a3d30a0c?s=96&d=mm&r=g\",\"caption\":\"R\u00e9daction\"},\"url\":\"https:\/\/elmawkie.dz\/fr\/author\/redaction\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Une campagne nationale de bilans m\u00e9dicaux pour les sportifs lanc\u00e9e depuis Oran - El Mawkie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/","og_locale":"fr_FR","og_type":"article","og_title":"Une campagne nationale de bilans m\u00e9dicaux pour les sportifs lanc\u00e9e depuis Oran","og_description":"L\u2019Association nationale alg\u00e9rienne de m\u00e9decine du sport (ANAMS) a entam\u00e9, depuis la wilaya d\u2019Oran, une vaste campagne nationale de bilans m\u00e9dicaux destin\u00e9e aux sportifs en pr\u00e9vision de la saison sportive 2026-2027. L\u2019op\u00e9ration sera progressivement d\u00e9ploy\u00e9e dans l\u2019ensemble des wilayas du pays, selon un communiqu\u00e9 rendu public mardi. Cette initiative vise \u00e0 renforcer le suivi m\u00e9dical &hellip;","og_url":"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/","og_site_name":"El Mawkie","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100088407094989&locale=fr_FR","article_published_time":"2026-07-14T10:03:01+00:00","article_modified_time":"2026-07-14T10:08:13+00:00","og_image":[{"width":1280,"height":778,"url":"https:\/\/elmawkie.dz\/fr\/wp-content\/uploads\/2026\/07\/14a15ec5-88d5-46a6-8310-938e3eb8ff54.jpeg","type":"image\/jpeg"}],"author":"R\u00e9daction","twitter_card":"summary_large_image","twitter_misc":{"Written by":"R\u00e9daction","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/#article","isPartOf":{"@id":"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/"},"author":{"name":"R\u00e9daction","@id":"https:\/\/elmawkie.dz\/fr\/#\/schema\/person\/e7bd59d6467874ba5c4723d8a9f0a63c"},"headline":"Une campagne nationale de bilans m\u00e9dicaux pour les sportifs lanc\u00e9e depuis Oran","datePublished":"2026-07-14T10:03:01+00:00","dateModified":"2026-07-14T10:08:13+00:00","mainEntityOfPage":{"@id":"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/"},"wordCount":291,"commentCount":0,"publisher":{"@id":"https:\/\/elmawkie.dz\/fr\/#organization"},"image":{"@id":"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/#primaryimage"},"thumbnailUrl":"https:\/\/elmawkie.dz\/fr\/wp-content\/uploads\/2026\/07\/14a15ec5-88d5-46a6-8310-938e3eb8ff54.jpeg","keywords":["ANAMS","Oran","sportifs","une campagne nationale"],"articleSection":["Sport"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/","url":"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/","name":"Une campagne nationale de bilans m\u00e9dicaux pour les sportifs lanc\u00e9e depuis Oran - El Mawkie","isPartOf":{"@id":"https:\/\/elmawkie.dz\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/#primaryimage"},"image":{"@id":"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/#primaryimage"},"thumbnailUrl":"https:\/\/elmawkie.dz\/fr\/wp-content\/uploads\/2026\/07\/14a15ec5-88d5-46a6-8310-938e3eb8ff54.jpeg","datePublished":"2026-07-14T10:03:01+00:00","dateModified":"2026-07-14T10:08:13+00:00","breadcrumb":{"@id":"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/#primaryimage","url":"https:\/\/elmawkie.dz\/fr\/wp-content\/uploads\/2026\/07\/14a15ec5-88d5-46a6-8310-938e3eb8ff54.jpeg","contentUrl":"https:\/\/elmawkie.dz\/fr\/wp-content\/uploads\/2026\/07\/14a15ec5-88d5-46a6-8310-938e3eb8ff54.jpeg","width":1280,"height":778},{"@type":"BreadcrumbList","@id":"https:\/\/elmawkie.dz\/fr\/une-campagne-nationale-de-bilans-medicaux-pour-les-sportifs-lancee-depuis-oran\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elmawkie.dz\/fr\/"},{"@type":"ListItem","position":2,"name":"Une campagne nationale de bilans m\u00e9dicaux pour les sportifs lanc\u00e9e depuis Oran"}]},{"@type":"WebSite","@id":"https:\/\/elmawkie.dz\/fr\/#website","url":"https:\/\/elmawkie.dz\/fr\/","name":"EL MAWKIE","description":"Journal \u00c9lectronique Alg\u00e9rien","publisher":{"@id":"https:\/\/elmawkie.dz\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elmawkie.dz\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/elmawkie.dz\/fr\/#organization","name":"EL MAWKIE","url":"https:\/\/elmawkie.dz\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/elmawkie.dz\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/elmawkie.dz\/fr\/wp-content\/uploads\/2024\/05\/logo1.png","contentUrl":"https:\/\/elmawkie.dz\/fr\/wp-content\/uploads\/2024\/05\/logo1.png","width":1648,"height":652,"caption":"EL MAWKIE"},"image":{"@id":"https:\/\/elmawkie.dz\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100088407094989&locale=fr_FR"]},{"@type":"Person","@id":"https:\/\/elmawkie.dz\/fr\/#\/schema\/person\/e7bd59d6467874ba5c4723d8a9f0a63c","name":"R\u00e9daction","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/elmawkie.dz\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f0f773456344da4d2788c054a3d30a0c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0f773456344da4d2788c054a3d30a0c?s=96&d=mm&r=g","caption":"R\u00e9daction"},"url":"https:\/\/elmawkie.dz\/fr\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/elmawkie.dz\/fr\/wp-json\/wp\/v2\/posts\/66272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elmawkie.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elmawkie.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elmawkie.dz\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/elmawkie.dz\/fr\/wp-json\/wp\/v2\/comments?post=66272"}],"version-history":[{"count":1,"href":"https:\/\/elmawkie.dz\/fr\/wp-json\/wp\/v2\/posts\/66272\/revisions"}],"predecessor-version":[{"id":66275,"href":"https:\/\/elmawkie.dz\/fr\/wp-json\/wp\/v2\/posts\/66272\/revisions\/66275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elmawkie.dz\/fr\/wp-json\/wp\/v2\/media\/66281"}],"wp:attachment":[{"href":"https:\/\/elmawkie.dz\/fr\/wp-json\/wp\/v2\/media?parent=66272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elmawkie.dz\/fr\/wp-json\/wp\/v2\/categories?post=66272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elmawkie.dz\/fr\/wp-json\/wp\/v2\/tags?post=66272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}